{"id":2718,"date":"2019-07-30T20:16:22","date_gmt":"2019-07-30T20:16:22","guid":{"rendered":"https:\/\/www.csogffhub.org\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/"},"modified":"2019-08-22T20:52:35","modified_gmt":"2019-08-22T20:52:35","slug":"lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage","status":"publish","type":"resources","link":"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/","title":{"rendered":"L&rsquo;Enregistrement du Webinaire sur Le CSO GFF Hub &#038; R\u00e9sultats du Sondage"},"content":{"rendered":"<p>L\u2019enregistrement et la pr\u00e9sentation de diapositives du webinaire sur le CSO GFF Hub &amp; r\u00e9sultats du sondage sont maintenant disponibles. Dans le webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u du Hub et Maty Dia ont pr\u00e9sent\u00e9 les r\u00e9sultats de l&rsquo;enqu\u00eate sur l\u2019engagement de la soci\u00e9t\u00e9 civile dans le processus du M\u00e9canisme de financement mondial (GFF).<\/p>\n<p>L&rsquo;enregistrement est disponible\u00a0<a href=\"https:\/\/zoom.us\/recording\/share\/EXH2J1GtikfeuKAu5XNc46nt1aRvWi8HbxBDJ8ZjSKmwIumekTziMw?startTime=1559044437000\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/zoom.us\/recording\/share\/EXH2J1GtikfeuKAu5XNc46nt1aRvWi8HbxBDJ8ZjSKmwIumekTziMw?startTime%3D1559044437000&amp;source=gmail&amp;ust=1564604310918000&amp;usg=AFQjCNGG0eiRNN4-tmurmuYswMq9yQD2Ug\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019enregistrement et la pr\u00e9sentation de diapositives du webinaire sur le CSO GFF Hub &amp; r\u00e9sultats du sondage sont maintenant disponibles. Dans le webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u du Hub et Maty Dia ont pr\u00e9sent\u00e9 les r\u00e9sultats de l&rsquo;enqu\u00eate sur l\u2019engagement de la soci\u00e9t\u00e9 civile dans le processus du M\u00e9canisme de financement mondial (GFF). [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_links_to":"","_links_to_target":""},"categories":[78],"Count":[],"language":[81],"Type_de_publication":[],"resource_themes":[95],"hub_publication_type":[102],"class_list":["post-2718","resources","type-resources","status-publish","hentry","category-societe-civile","language-english-fr","resource_themes-engagement-et-soutien","hub_publication_type-guide-de-plaidoyer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Enregistrement du Webinaire sur Le CSO GFF Hub &amp; R\u00e9sultats du Sondage - GFF Hub<\/title>\n<meta name=\"description\" content=\"Les diapositives d\u2019enregistrement et de pr\u00e9sentation du webinaire sur le CSO GFF Hub et les r\u00e9sultats de l\u2019enqu\u00eate sur les besoins et les actifs des CSO sont maintenant disponibles. Lors du webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u de The Hub et Maty Dia a pr\u00e9sent\u00e9 les r\u00e9sultats d&#039;une enqu\u00eate sur les besoins et les atouts des organisations de la soci\u00e9t\u00e9 civile (OSC) travaillant sur le GFF.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Enregistrement du Webinaire sur Le CSO GFF Hub &amp; R\u00e9sultats du Sondage - GFF Hub\" \/>\n<meta property=\"og:description\" content=\"Les diapositives d\u2019enregistrement et de pr\u00e9sentation du webinaire sur le CSO GFF Hub et les r\u00e9sultats de l\u2019enqu\u00eate sur les besoins et les actifs des CSO sont maintenant disponibles. Lors du webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u de The Hub et Maty Dia a pr\u00e9sent\u00e9 les r\u00e9sultats d&#039;une enqu\u00eate sur les besoins et les atouts des organisations de la soci\u00e9t\u00e9 civile (OSC) travaillant sur le GFF.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/\" \/>\n<meta property=\"og:site_name\" content=\"GFF Hub\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-22T20:52:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/resources\\\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\\\/\",\"url\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/resources\\\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\\\/\",\"name\":\"L'Enregistrement du Webinaire sur Le CSO GFF Hub & R\u00e9sultats du Sondage - GFF Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/#website\"},\"datePublished\":\"2019-07-30T20:16:22+00:00\",\"dateModified\":\"2019-08-22T20:52:35+00:00\",\"description\":\"Les diapositives d\u2019enregistrement et de pr\u00e9sentation du webinaire sur le CSO GFF Hub et les r\u00e9sultats de l\u2019enqu\u00eate sur les besoins et les actifs des CSO sont maintenant disponibles. Lors du webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u de The Hub et Maty Dia a pr\u00e9sent\u00e9 les r\u00e9sultats d'une enqu\u00eate sur les besoins et les atouts des organisations de la soci\u00e9t\u00e9 civile (OSC) travaillant sur le GFF.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/resources\\\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/resources\\\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/resources\\\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/gff-hub\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hub Resources\",\"item\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&rsquo;Enregistrement du Webinaire sur Le CSO GFF Hub &#038; R\u00e9sultats du Sondage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/\",\"name\":\"GFF Hub\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/#organization\",\"name\":\"GFF Hub\",\"url\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.csogffhub.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/gff-cso-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.csogffhub.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/gff-cso-logo-1.png\",\"width\":1245,\"height\":734,\"caption\":\"GFF Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/www.csogffhub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Enregistrement du Webinaire sur Le CSO GFF Hub & R\u00e9sultats du Sondage - GFF Hub","description":"Les diapositives d\u2019enregistrement et de pr\u00e9sentation du webinaire sur le CSO GFF Hub et les r\u00e9sultats de l\u2019enqu\u00eate sur les besoins et les actifs des CSO sont maintenant disponibles. Lors du webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u de The Hub et Maty Dia a pr\u00e9sent\u00e9 les r\u00e9sultats d'une enqu\u00eate sur les besoins et les atouts des organisations de la soci\u00e9t\u00e9 civile (OSC) travaillant sur le GFF.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Enregistrement du Webinaire sur Le CSO GFF Hub & R\u00e9sultats du Sondage - GFF Hub","og_description":"Les diapositives d\u2019enregistrement et de pr\u00e9sentation du webinaire sur le CSO GFF Hub et les r\u00e9sultats de l\u2019enqu\u00eate sur les besoins et les actifs des CSO sont maintenant disponibles. Lors du webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u de The Hub et Maty Dia a pr\u00e9sent\u00e9 les r\u00e9sultats d'une enqu\u00eate sur les besoins et les atouts des organisations de la soci\u00e9t\u00e9 civile (OSC) travaillant sur le GFF.","og_url":"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/","og_site_name":"GFF Hub","article_modified_time":"2019-08-22T20:52:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/","url":"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/","name":"L'Enregistrement du Webinaire sur Le CSO GFF Hub & R\u00e9sultats du Sondage - GFF Hub","isPartOf":{"@id":"https:\/\/www.csogffhub.org\/fr\/#website"},"datePublished":"2019-07-30T20:16:22+00:00","dateModified":"2019-08-22T20:52:35+00:00","description":"Les diapositives d\u2019enregistrement et de pr\u00e9sentation du webinaire sur le CSO GFF Hub et les r\u00e9sultats de l\u2019enqu\u00eate sur les besoins et les actifs des CSO sont maintenant disponibles. Lors du webinaire, Suzanna Dennis a donn\u00e9 un aper\u00e7u de The Hub et Maty Dia a pr\u00e9sent\u00e9 les r\u00e9sultats d'une enqu\u00eate sur les besoins et les atouts des organisations de la soci\u00e9t\u00e9 civile (OSC) travaillant sur le GFF.","breadcrumb":{"@id":"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.csogffhub.org\/fr\/resources\/lenregistrement-du-webinaire-sur-le-cso-gff-hub-resultats-du-sondage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csogffhub.org\/fr\/gff-hub\/"},{"@type":"ListItem","position":2,"name":"Hub Resources","item":"https:\/\/www.csogffhub.org\/fr\/resources\/"},{"@type":"ListItem","position":3,"name":"L&rsquo;Enregistrement du Webinaire sur Le CSO GFF Hub &#038; R\u00e9sultats du Sondage"}]},{"@type":"WebSite","@id":"https:\/\/www.csogffhub.org\/fr\/#website","url":"https:\/\/www.csogffhub.org\/fr\/","name":"GFF Hub","description":"","publisher":{"@id":"https:\/\/www.csogffhub.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csogffhub.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.csogffhub.org\/fr\/#organization","name":"GFF Hub","url":"https:\/\/www.csogffhub.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.csogffhub.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.csogffhub.org\/wp-content\/uploads\/2023\/04\/gff-cso-logo-1.png","contentUrl":"https:\/\/www.csogffhub.org\/wp-content\/uploads\/2023\/04\/gff-cso-logo-1.png","width":1245,"height":734,"caption":"GFF Hub"},"image":{"@id":"https:\/\/www.csogffhub.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/resources\/2718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/types\/resources"}],"author":[{"embeddable":true,"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/users\/6"}],"wp:attachment":[{"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/media?parent=2718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/categories?post=2718"},{"taxonomy":"Count","embeddable":true,"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/Count?post=2718"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/language?post=2718"},{"taxonomy":"Type_de_publication","embeddable":true,"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/Type_de_publication?post=2718"},{"taxonomy":"resource_themes","embeddable":true,"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/resource_themes?post=2718"},{"taxonomy":"hub_publication_type","embeddable":true,"href":"https:\/\/www.csogffhub.org\/fr\/wp-json\/wp\/v2\/hub_publication_type?post=2718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}